{"id":238,"count":0,"description":"","link":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/","name":"Portugal - Azores","slug":"portugal-azores","taxonomy":"country_and_regions","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portugal - Azores Archives - EWWR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portugal - Azores Archives - EWWR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/\" \/>\n<meta property=\"og:site_name\" content=\"EWWR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"613\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@2EWWR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/country_and_regions\\\/portugal-azores\\\/\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/country_and_regions\\\/portugal-azores\\\/\",\"name\":\"Portugal - Azores Archives - EWWR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/country_and_regions\\\/portugal-azores\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/country_and_regions\\\/portugal-azores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ewwr.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portugal - Azores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/\",\"name\":\"EWWR\",\"description\":\"European Week for Waste Reduction\",\"publisher\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/#organization\",\"name\":\"European Week for Waste Reduction\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/EWWR_logo_pin.png\",\"contentUrl\":\"https:\\\/\\\/ewwr.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/EWWR_logo_pin.png\",\"width\":256,\"height\":256,\"caption\":\"European Week for Waste Reduction\"},\"image\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ewwr.eu\\\/\",\"https:\\\/\\\/x.com\\\/2EWWR\",\"https:\\\/\\\/www.instagram.com\\\/2ewwr\\\/\",\"https:\\\/\\\/www.youtube.com\\\/ewwrsecretariat\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Settimana_europea_per_la_riduzione_dei_rifiuti\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portugal - Azores Archives - EWWR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/","og_locale":"fr_FR","og_type":"article","og_title":"Portugal - Azores Archives - EWWR","og_url":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/","og_site_name":"EWWR","og_image":[{"width":613,"height":186,"url":"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@2EWWR","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/","url":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/","name":"Portugal - Azores Archives - EWWR","isPartOf":{"@id":"https:\/\/ewwr.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/ewwr.eu\/fr\/country_and_regions\/portugal-azores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ewwr.eu\/"},{"@type":"ListItem","position":2,"name":"Portugal - Azores"}]},{"@type":"WebSite","@id":"https:\/\/ewwr.eu\/fr\/#website","url":"https:\/\/ewwr.eu\/fr\/","name":"EWWR","description":"European Week for Waste Reduction","publisher":{"@id":"https:\/\/ewwr.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ewwr.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ewwr.eu\/fr\/#organization","name":"European Week for Waste Reduction","url":"https:\/\/ewwr.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ewwr.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_pin.png","contentUrl":"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_pin.png","width":256,"height":256,"caption":"European Week for Waste Reduction"},"image":{"@id":"https:\/\/ewwr.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ewwr.eu\/","https:\/\/x.com\/2EWWR","https:\/\/www.instagram.com\/2ewwr\/","https:\/\/www.youtube.com\/ewwrsecretariat","https:\/\/it.wikipedia.org\/wiki\/Settimana_europea_per_la_riduzione_dei_rifiuti"]}]}},"_links":{"self":[{"href":"https:\/\/ewwr.eu\/fr\/wp-json\/wp\/v2\/country_and_regions\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ewwr.eu\/fr\/wp-json\/wp\/v2\/country_and_regions"}],"about":[{"href":"https:\/\/ewwr.eu\/fr\/wp-json\/wp\/v2\/taxonomies\/country_and_regions"}],"wp:post_type":[{"href":"https:\/\/ewwr.eu\/fr\/wp-json\/wp\/v2\/actions?country_and_regions=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}