{"id":2876,"count":5,"description":"","link":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/","name":"\u0395\u03c0\u03b1\u03bd\u03b5\u03be\u03ad\u03c4\u03b1\u03c3\u03b7","slug":"r1-rethink","taxonomy":"action_theme","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rethink Archives - EWWR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rethink Archives - EWWR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/\" \/>\n<meta property=\"og:site_name\" content=\"EWWR\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"613\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@2EWWR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/action_theme\\\/r1-rethink\\\/\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/action_theme\\\/r1-rethink\\\/\",\"name\":\"Rethink Archives - EWWR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/action_theme\\\/r1-rethink\\\/#breadcrumb\"},\"inLanguage\":\"el\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/action_theme\\\/r1-rethink\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ewwr.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rethink\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/#website\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/\",\"name\":\"EWWR\",\"description\":\"European Week for Waste Reduction\",\"publisher\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/#organization\",\"name\":\"European Week for Waste Reduction\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ewwr.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/EWWR_logo_pin.png\",\"contentUrl\":\"https:\\\/\\\/ewwr.eu\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/EWWR_logo_pin.png\",\"width\":256,\"height\":256,\"caption\":\"European Week for Waste Reduction\"},\"image\":{\"@id\":\"https:\\\/\\\/ewwr.eu\\\/el\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ewwr.eu\\\/\",\"https:\\\/\\\/x.com\\\/2EWWR\",\"https:\\\/\\\/www.instagram.com\\\/2ewwr\\\/\",\"https:\\\/\\\/www.youtube.com\\\/ewwrsecretariat\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Settimana_europea_per_la_riduzione_dei_rifiuti\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rethink Archives - EWWR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/","og_locale":"el_GR","og_type":"article","og_title":"Rethink Archives - EWWR","og_url":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/","og_site_name":"EWWR","og_image":[{"width":613,"height":186,"url":"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@2EWWR","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/","url":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/","name":"Rethink Archives - EWWR","isPartOf":{"@id":"https:\/\/ewwr.eu\/el\/#website"},"breadcrumb":{"@id":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/#breadcrumb"},"inLanguage":"el"},{"@type":"BreadcrumbList","@id":"https:\/\/ewwr.eu\/el\/action_theme\/r1-rethink\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ewwr.eu\/"},{"@type":"ListItem","position":2,"name":"Rethink"}]},{"@type":"WebSite","@id":"https:\/\/ewwr.eu\/el\/#website","url":"https:\/\/ewwr.eu\/el\/","name":"EWWR","description":"European Week for Waste Reduction","publisher":{"@id":"https:\/\/ewwr.eu\/el\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ewwr.eu\/el\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/ewwr.eu\/el\/#organization","name":"European Week for Waste Reduction","url":"https:\/\/ewwr.eu\/el\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/ewwr.eu\/el\/#\/schema\/logo\/image\/","url":"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_pin.png","contentUrl":"https:\/\/ewwr.eu\/wp-content\/uploads\/2020\/08\/EWWR_logo_pin.png","width":256,"height":256,"caption":"European Week for Waste Reduction"},"image":{"@id":"https:\/\/ewwr.eu\/el\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ewwr.eu\/","https:\/\/x.com\/2EWWR","https:\/\/www.instagram.com\/2ewwr\/","https:\/\/www.youtube.com\/ewwrsecretariat","https:\/\/it.wikipedia.org\/wiki\/Settimana_europea_per_la_riduzione_dei_rifiuti"]}]}},"_links":{"self":[{"href":"https:\/\/ewwr.eu\/el\/wp-json\/wp\/v2\/action_theme\/2876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ewwr.eu\/el\/wp-json\/wp\/v2\/action_theme"}],"about":[{"href":"https:\/\/ewwr.eu\/el\/wp-json\/wp\/v2\/taxonomies\/action_theme"}],"wp:post_type":[{"href":"https:\/\/ewwr.eu\/el\/wp-json\/wp\/v2\/actions?action_theme=2876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}